{"id":29683,"date":"2022-05-12T11:34:34","date_gmt":"2022-05-12T11:34:34","guid":{"rendered":"https:\/\/occoprojects.com\/projects\/sorainen\/"},"modified":"2023-06-28T10:54:54","modified_gmt":"2023-06-28T10:54:54","slug":"sorainen","status":"publish","type":"project","link":"https:\/\/occoprojects.com\/ro\/projekte\/sorainen\/","title":{"rendered":"Sorainen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":28839,"parent":0,"template":"","project-category":[72],"class_list":["post-29683","project","type-project","status-publish","has-post-thumbnail","hentry","project-category-offices-ro"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sorainen - OCCO<\/title>\n<meta name=\"description\" content=\"Mobilier \u0219i accesorii, livrare \u0219i instalare, management de proiect cu tehnologie personalizat\u0103 bazat\u0103 pe AI pentru a accelera fluxurile de proiect.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/occoprojects.com\/ro\/projekte\/sorainen\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sorainen - OCCO\" \/>\n<meta property=\"og:description\" content=\"Mobilier \u0219i accesorii, livrare \u0219i instalare, management de proiect cu tehnologie personalizat\u0103 bazat\u0103 pe AI pentru a accelera fluxurile de proiect.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/occoprojects.com\/ro\/projekte\/sorainen\/\" \/>\n<meta property=\"og:site_name\" content=\"OCCO\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-28T10:54:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/occoprojects.com\/wp-content\/uploads\/2023\/04\/Rotermanni-6_091.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/projekte\\\/sorainen\\\/\",\"url\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/projekte\\\/sorainen\\\/\",\"name\":\"Sorainen - OCCO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/projekte\\\/sorainen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/projekte\\\/sorainen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/occoprojects.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Rotermanni-6_091.jpg\",\"datePublished\":\"2022-05-12T11:34:34+00:00\",\"dateModified\":\"2023-06-28T10:54:54+00:00\",\"description\":\"Mobilier \u0219i accesorii, livrare \u0219i instalare, management de proiect cu tehnologie personalizat\u0103 bazat\u0103 pe AI pentru a accelera fluxurile de proiect.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/projekte\\\/sorainen\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/occoprojects.com\\\/ro\\\/projekte\\\/sorainen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/projekte\\\/sorainen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/occoprojects.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Rotermanni-6_091.jpg\",\"contentUrl\":\"https:\\\/\\\/occoprojects.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Rotermanni-6_091.jpg\",\"width\":2500,\"height\":1667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/projekte\\\/sorainen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"References\",\"item\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/projekte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sorainen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/#website\",\"url\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/\",\"name\":\"OCCO\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sorainen - OCCO","description":"Mobilier \u0219i accesorii, livrare \u0219i instalare, management de proiect cu tehnologie personalizat\u0103 bazat\u0103 pe AI pentru a accelera fluxurile de proiect.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/occoprojects.com\/ro\/projekte\/sorainen\/","og_locale":"ro_RO","og_type":"article","og_title":"Sorainen - OCCO","og_description":"Mobilier \u0219i accesorii, livrare \u0219i instalare, management de proiect cu tehnologie personalizat\u0103 bazat\u0103 pe AI pentru a accelera fluxurile de proiect.","og_url":"https:\/\/occoprojects.com\/ro\/projekte\/sorainen\/","og_site_name":"OCCO","article_modified_time":"2023-06-28T10:54:54+00:00","og_image":[{"width":2500,"height":1667,"url":"https:\/\/occoprojects.com\/wp-content\/uploads\/2023\/04\/Rotermanni-6_091.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/occoprojects.com\/ro\/projekte\/sorainen\/","url":"https:\/\/occoprojects.com\/ro\/projekte\/sorainen\/","name":"Sorainen - OCCO","isPartOf":{"@id":"https:\/\/occoprojects.com\/ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/occoprojects.com\/ro\/projekte\/sorainen\/#primaryimage"},"image":{"@id":"https:\/\/occoprojects.com\/ro\/projekte\/sorainen\/#primaryimage"},"thumbnailUrl":"https:\/\/occoprojects.com\/wp-content\/uploads\/2023\/04\/Rotermanni-6_091.jpg","datePublished":"2022-05-12T11:34:34+00:00","dateModified":"2023-06-28T10:54:54+00:00","description":"Mobilier \u0219i accesorii, livrare \u0219i instalare, management de proiect cu tehnologie personalizat\u0103 bazat\u0103 pe AI pentru a accelera fluxurile de proiect.","breadcrumb":{"@id":"https:\/\/occoprojects.com\/ro\/projekte\/sorainen\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/occoprojects.com\/ro\/projekte\/sorainen\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/occoprojects.com\/ro\/projekte\/sorainen\/#primaryimage","url":"https:\/\/occoprojects.com\/wp-content\/uploads\/2023\/04\/Rotermanni-6_091.jpg","contentUrl":"https:\/\/occoprojects.com\/wp-content\/uploads\/2023\/04\/Rotermanni-6_091.jpg","width":2500,"height":1667},{"@type":"BreadcrumbList","@id":"https:\/\/occoprojects.com\/ro\/projekte\/sorainen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/occoprojects.com\/ro\/"},{"@type":"ListItem","position":2,"name":"References","item":"https:\/\/occoprojects.com\/ro\/projekte\/"},{"@type":"ListItem","position":3,"name":"Sorainen"}]},{"@type":"WebSite","@id":"https:\/\/occoprojects.com\/ro\/#website","url":"https:\/\/occoprojects.com\/ro\/","name":"OCCO","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/occoprojects.com\/ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/occoprojects.com\/ro\/wp-json\/wp\/v2\/project\/29683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/occoprojects.com\/ro\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/occoprojects.com\/ro\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/occoprojects.com\/ro\/wp-json\/wp\/v2\/media\/28839"}],"wp:attachment":[{"href":"https:\/\/occoprojects.com\/ro\/wp-json\/wp\/v2\/media?parent=29683"}],"wp:term":[{"taxonomy":"project-category","embeddable":true,"href":"https:\/\/occoprojects.com\/ro\/wp-json\/wp\/v2\/project-category?post=29683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}