{"id":29663,"date":"2022-05-11T15:23:03","date_gmt":"2022-05-11T15:23:03","guid":{"rendered":"https:\/\/occoprojects.com\/projects\/nabuminds\/"},"modified":"2023-06-28T10:48:55","modified_gmt":"2023-06-28T10:48:55","slug":"nabuminds","status":"publish","type":"project","link":"https:\/\/occoprojects.com\/ro\/projekte\/nabuminds\/","title":{"rendered":"NabuMinds"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":28957,"parent":0,"template":"","project-category":[72],"class_list":["post-29663","project","type-project","status-publish","has-post-thumbnail","hentry","project-category-offices-ro"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NabuMinds - OCCO<\/title>\n<meta name=\"description\" content=\"Mobilier \u0219i accesorii, livrare \u0219i instalare, management de proiect cu tehnologie personalizat\u0103 bazat\u0103 pe AI pentru a accelera fluxurile de proiect.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/occoprojects.com\/ro\/projekte\/nabuminds\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NabuMinds - OCCO\" \/>\n<meta property=\"og:description\" content=\"Mobilier \u0219i accesorii, livrare \u0219i instalare, management de proiect cu tehnologie personalizat\u0103 bazat\u0103 pe AI pentru a accelera fluxurile de proiect.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/occoprojects.com\/ro\/projekte\/nabuminds\/\" \/>\n<meta property=\"og:site_name\" content=\"OCCO\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-28T10:48:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/occoprojects.com\/wp-content\/uploads\/2023\/04\/nabuminds-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/projekte\\\/nabuminds\\\/\",\"url\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/projekte\\\/nabuminds\\\/\",\"name\":\"NabuMinds - OCCO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/projekte\\\/nabuminds\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/projekte\\\/nabuminds\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/occoprojects.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/nabuminds.jpg\",\"datePublished\":\"2022-05-11T15:23:03+00:00\",\"dateModified\":\"2023-06-28T10:48:55+00:00\",\"description\":\"Mobilier \u0219i accesorii, livrare \u0219i instalare, management de proiect cu tehnologie personalizat\u0103 bazat\u0103 pe AI pentru a accelera fluxurile de proiect.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/projekte\\\/nabuminds\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/occoprojects.com\\\/ro\\\/projekte\\\/nabuminds\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/projekte\\\/nabuminds\\\/#primaryimage\",\"url\":\"https:\\\/\\\/occoprojects.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/nabuminds.jpg\",\"contentUrl\":\"https:\\\/\\\/occoprojects.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/nabuminds.jpg\",\"width\":2500,\"height\":1667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/projekte\\\/nabuminds\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"References\",\"item\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/projekte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"NabuMinds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/#website\",\"url\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/\",\"name\":\"OCCO\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/occoprojects.com\\\/ro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NabuMinds - OCCO","description":"Mobilier \u0219i accesorii, livrare \u0219i instalare, management de proiect cu tehnologie personalizat\u0103 bazat\u0103 pe AI pentru a accelera fluxurile de proiect.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/occoprojects.com\/ro\/projekte\/nabuminds\/","og_locale":"ro_RO","og_type":"article","og_title":"NabuMinds - OCCO","og_description":"Mobilier \u0219i accesorii, livrare \u0219i instalare, management de proiect cu tehnologie personalizat\u0103 bazat\u0103 pe AI pentru a accelera fluxurile de proiect.","og_url":"https:\/\/occoprojects.com\/ro\/projekte\/nabuminds\/","og_site_name":"OCCO","article_modified_time":"2023-06-28T10:48:55+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/occoprojects.com\/wp-content\/uploads\/2023\/04\/nabuminds-1024x683.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/occoprojects.com\/ro\/projekte\/nabuminds\/","url":"https:\/\/occoprojects.com\/ro\/projekte\/nabuminds\/","name":"NabuMinds - OCCO","isPartOf":{"@id":"https:\/\/occoprojects.com\/ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/occoprojects.com\/ro\/projekte\/nabuminds\/#primaryimage"},"image":{"@id":"https:\/\/occoprojects.com\/ro\/projekte\/nabuminds\/#primaryimage"},"thumbnailUrl":"https:\/\/occoprojects.com\/wp-content\/uploads\/2023\/04\/nabuminds.jpg","datePublished":"2022-05-11T15:23:03+00:00","dateModified":"2023-06-28T10:48:55+00:00","description":"Mobilier \u0219i accesorii, livrare \u0219i instalare, management de proiect cu tehnologie personalizat\u0103 bazat\u0103 pe AI pentru a accelera fluxurile de proiect.","breadcrumb":{"@id":"https:\/\/occoprojects.com\/ro\/projekte\/nabuminds\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/occoprojects.com\/ro\/projekte\/nabuminds\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/occoprojects.com\/ro\/projekte\/nabuminds\/#primaryimage","url":"https:\/\/occoprojects.com\/wp-content\/uploads\/2023\/04\/nabuminds.jpg","contentUrl":"https:\/\/occoprojects.com\/wp-content\/uploads\/2023\/04\/nabuminds.jpg","width":2500,"height":1667},{"@type":"BreadcrumbList","@id":"https:\/\/occoprojects.com\/ro\/projekte\/nabuminds\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/occoprojects.com\/ro\/"},{"@type":"ListItem","position":2,"name":"References","item":"https:\/\/occoprojects.com\/ro\/projekte\/"},{"@type":"ListItem","position":3,"name":"NabuMinds"}]},{"@type":"WebSite","@id":"https:\/\/occoprojects.com\/ro\/#website","url":"https:\/\/occoprojects.com\/ro\/","name":"OCCO","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/occoprojects.com\/ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/occoprojects.com\/ro\/wp-json\/wp\/v2\/project\/29663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/occoprojects.com\/ro\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/occoprojects.com\/ro\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/occoprojects.com\/ro\/wp-json\/wp\/v2\/media\/28957"}],"wp:attachment":[{"href":"https:\/\/occoprojects.com\/ro\/wp-json\/wp\/v2\/media?parent=29663"}],"wp:term":[{"taxonomy":"project-category","embeddable":true,"href":"https:\/\/occoprojects.com\/ro\/wp-json\/wp\/v2\/project-category?post=29663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}