{"id":29676,"date":"2022-06-14T16:14:39","date_gmt":"2022-06-14T16:14:39","guid":{"rendered":"https:\/\/occoprojects.com\/projects\/esvika\/"},"modified":"2023-06-28T12:22:51","modified_gmt":"2023-06-28T12:22:51","slug":"esvika","status":"publish","type":"project","link":"https:\/\/occoprojects.com\/de\/projekte\/esvika\/","title":{"rendered":"Esvika"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":28934,"parent":0,"template":"","project-category":[58],"class_list":["post-29676","project","type-project","status-publish","has-post-thumbnail","hentry","project-category-buros"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Esvika - OCCO<\/title>\n<meta name=\"description\" content=\"M\u00f6bel und Einrichtung, Lieferung und Installation mit ma\u00dfgeschneiderter KI-gest\u00fctzter Technologie zur Beschleunigung des Projektablaufs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/occoprojects.com\/de\/projekte\/esvika\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esvika - OCCO\" \/>\n<meta property=\"og:description\" content=\"M\u00f6bel und Einrichtung, Lieferung und Installation mit ma\u00dfgeschneiderter KI-gest\u00fctzter Technologie zur Beschleunigung des Projektablaufs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/occoprojects.com\/de\/projekte\/esvika\/\" \/>\n<meta property=\"og:site_name\" content=\"OCCO\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-28T12:22:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/occoprojects.com\/wp-content\/uploads\/2023\/04\/Peterburi-tee-100_057.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/occoprojects.com\\\/de\\\/projekte\\\/esvika\\\/\",\"url\":\"https:\\\/\\\/occoprojects.com\\\/de\\\/projekte\\\/esvika\\\/\",\"name\":\"Esvika - OCCO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/occoprojects.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/occoprojects.com\\\/de\\\/projekte\\\/esvika\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/occoprojects.com\\\/de\\\/projekte\\\/esvika\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/occoprojects.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Peterburi-tee-100_057.jpg\",\"datePublished\":\"2022-06-14T16:14:39+00:00\",\"dateModified\":\"2023-06-28T12:22:51+00:00\",\"description\":\"M\u00f6bel und Einrichtung, Lieferung und Installation mit ma\u00dfgeschneiderter KI-gest\u00fctzter Technologie zur Beschleunigung des Projektablaufs.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/occoprojects.com\\\/de\\\/projekte\\\/esvika\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/occoprojects.com\\\/de\\\/projekte\\\/esvika\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/occoprojects.com\\\/de\\\/projekte\\\/esvika\\\/#primaryimage\",\"url\":\"https:\\\/\\\/occoprojects.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Peterburi-tee-100_057.jpg\",\"contentUrl\":\"https:\\\/\\\/occoprojects.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Peterburi-tee-100_057.jpg\",\"width\":2500,\"height\":1667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/occoprojects.com\\\/de\\\/projekte\\\/esvika\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/occoprojects.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"References\",\"item\":\"https:\\\/\\\/occoprojects.com\\\/de\\\/projekte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Esvika\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/occoprojects.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/occoprojects.com\\\/de\\\/\",\"name\":\"OCCO\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/occoprojects.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esvika - OCCO","description":"M\u00f6bel und Einrichtung, Lieferung und Installation mit ma\u00dfgeschneiderter KI-gest\u00fctzter Technologie zur Beschleunigung des Projektablaufs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/occoprojects.com\/de\/projekte\/esvika\/","og_locale":"de_DE","og_type":"article","og_title":"Esvika - OCCO","og_description":"M\u00f6bel und Einrichtung, Lieferung und Installation mit ma\u00dfgeschneiderter KI-gest\u00fctzter Technologie zur Beschleunigung des Projektablaufs.","og_url":"https:\/\/occoprojects.com\/de\/projekte\/esvika\/","og_site_name":"OCCO","article_modified_time":"2023-06-28T12:22:51+00:00","og_image":[{"width":2500,"height":1667,"url":"https:\/\/occoprojects.com\/wp-content\/uploads\/2023\/04\/Peterburi-tee-100_057.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/occoprojects.com\/de\/projekte\/esvika\/","url":"https:\/\/occoprojects.com\/de\/projekte\/esvika\/","name":"Esvika - OCCO","isPartOf":{"@id":"https:\/\/occoprojects.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/occoprojects.com\/de\/projekte\/esvika\/#primaryimage"},"image":{"@id":"https:\/\/occoprojects.com\/de\/projekte\/esvika\/#primaryimage"},"thumbnailUrl":"https:\/\/occoprojects.com\/wp-content\/uploads\/2023\/04\/Peterburi-tee-100_057.jpg","datePublished":"2022-06-14T16:14:39+00:00","dateModified":"2023-06-28T12:22:51+00:00","description":"M\u00f6bel und Einrichtung, Lieferung und Installation mit ma\u00dfgeschneiderter KI-gest\u00fctzter Technologie zur Beschleunigung des Projektablaufs.","breadcrumb":{"@id":"https:\/\/occoprojects.com\/de\/projekte\/esvika\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/occoprojects.com\/de\/projekte\/esvika\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/occoprojects.com\/de\/projekte\/esvika\/#primaryimage","url":"https:\/\/occoprojects.com\/wp-content\/uploads\/2023\/04\/Peterburi-tee-100_057.jpg","contentUrl":"https:\/\/occoprojects.com\/wp-content\/uploads\/2023\/04\/Peterburi-tee-100_057.jpg","width":2500,"height":1667},{"@type":"BreadcrumbList","@id":"https:\/\/occoprojects.com\/de\/projekte\/esvika\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/occoprojects.com\/de\/"},{"@type":"ListItem","position":2,"name":"References","item":"https:\/\/occoprojects.com\/de\/projekte\/"},{"@type":"ListItem","position":3,"name":"Esvika"}]},{"@type":"WebSite","@id":"https:\/\/occoprojects.com\/de\/#website","url":"https:\/\/occoprojects.com\/de\/","name":"OCCO","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/occoprojects.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"}]}},"_links":{"self":[{"href":"https:\/\/occoprojects.com\/de\/wp-json\/wp\/v2\/project\/29676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/occoprojects.com\/de\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/occoprojects.com\/de\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/occoprojects.com\/de\/wp-json\/wp\/v2\/media\/28934"}],"wp:attachment":[{"href":"https:\/\/occoprojects.com\/de\/wp-json\/wp\/v2\/media?parent=29676"}],"wp:term":[{"taxonomy":"project-category","embeddable":true,"href":"https:\/\/occoprojects.com\/de\/wp-json\/wp\/v2\/project-category?post=29676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}